{"id":405850,"date":"2025-05-08T16:51:58","date_gmt":"2025-05-08T13:51:58","guid":{"rendered":"https:\/\/nbg.eu\/product\/surefire-scout-infrared-light-m640v-pro-tan\/"},"modified":"2026-01-21T11:38:19","modified_gmt":"2026-01-21T08:38:19","slug":"surefire-scout-infrarotlicht-m640v-pro-tan","status":"publish","type":"product","link":"https:\/\/nbg.eu\/de\/produkt\/surefire-scout-infrarotlicht-m640v-pro-tan\/","title":{"rendered":"SureFire Scout Infrarotlicht &#8211; M640V PRO &#8211; Tan"},"content":{"rendered":"<h2>SureFire Scout Infrarotlicht &#8211; M640V PRO &#8211; Tan<\/h2>\n<p>Der M640V PRO Scout Infrarotlicht bietet folgende Eigenschaften:<\/p>\n<ul>\n<li>350 Lumen wei\u00dfes Licht und 120 mW IR-Leistung<\/li>\n<li>Neue Flachmontage f\u00fcr optimale Positionierung auf MIL-STD-1913 oder M-LOK Schienen<\/li>\n<li>Spezielle TIR-Linse f\u00fcr weitreichenden Strahl mit ausreichendem Umgebungslicht<\/li>\n<li>Schnelles Umschalten zwischen Wei\u00df- und IR-Modi<\/li>\n<li>Robuste Konstruktion aus Luft- und Raumfahrtaluminium mit hartanodisierter Oberfl\u00e4che nach Milit\u00e4rstandard<\/li>\n<li>IPX7 Wasserdichtigkeit<\/li>\n<li>Druckknopfschalter am Endst\u00fcck f\u00fcr einfache Aktivierung<\/li>\n<\/ul>\n<p>Mit 2,5 Stunden Laufzeit auf hoher Stufe und einer Strahldistanz von 214 Metern ist der M640V PRO f\u00fcr mittlere bis lange Reichweiten geeignet. Das Ger\u00e4t nutzt die Technologie von SureFire.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vielseitige IR\/Wei\u00df-Waffenleuchte mit 350 Lumen und 120 mW IR-Leistung.<\/p>\n","protected":false},"featured_media":353020,"template":"","meta":{"_acf_changed":false},"product_brand":[11870],"product_cat":[12069,12096,12038],"product_tag":[],"class_list":{"0":"post-405850","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-surefire","7":"product_cat-edc-lichter","8":"product_cat-gewehr-lampen","9":"product_cat-lichter","11":"first","12":"instock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/nbg.eu\/de\/wp-json\/wp\/v2\/product\/405850","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nbg.eu\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/nbg.eu\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nbg.eu\/de\/wp-json\/wp\/v2\/media\/353020"}],"wp:attachment":[{"href":"https:\/\/nbg.eu\/de\/wp-json\/wp\/v2\/media?parent=405850"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/nbg.eu\/de\/wp-json\/wp\/v2\/product_brand?post=405850"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/nbg.eu\/de\/wp-json\/wp\/v2\/product_cat?post=405850"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/nbg.eu\/de\/wp-json\/wp\/v2\/product_tag?post=405850"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}