{"id":44945,"date":"2024-08-18T12:31:43","date_gmt":"2024-08-18T09:31:43","guid":{"rendered":"https:\/\/nbg.eu\/product\/daa-reloading-hex-key-set\/"},"modified":"2026-01-21T12:01:46","modified_gmt":"2026-01-21T09:01:46","slug":"juego-de-llaves-hexagonales-recarga-daa","status":"publish","type":"product","link":"https:\/\/nbg.eu\/es\/producto\/juego-de-llaves-hexagonales-recarga-daa\/","title":{"rendered":"Juego de Llaves Hexagonales Recarga Daa"},"content":{"rendered":"<p>Mejore su experiencia de recarga con el Juego de Llaves Hexagonales DAA para Recarga. Este juego de 7 piezas de llaves Allen largas con punta de bola cuenta con:<\/p>\n<ul>\n<li>Construcci\u00f3n de alta calidad<\/li>\n<li>Hombros recubiertos de vinilo rojo brillante para mayor visibilidad<\/li>\n<li>Perfectas para prensas Dillon y otras marcas fabricadas en EE. UU.<\/li>\n<li>Tama\u00f1os: 5\/64&#8243;, 3\/32&#8243;, 1\/8&#8243;, 9\/64&#8243;, 5\/32&#8243;, 3\/16&#8243;, 1\/4&#8243;<\/li>\n<\/ul>\n<p>Complemento ideal para el Portaherramientas de Prensa de Recarga DAA.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Juego de 7 llaves Allen con cabeza de bola para prensas de recarga de EE. UU. Vinilo rojo.<\/p>\n","protected":false},"featured_media":27157,"template":"","meta":{"_acf_changed":false},"product_brand":[11277],"product_cat":[12254,12265],"product_tag":[],"class_list":{"0":"post-44945","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-doublealpha","7":"product_cat-accesorios-de-recarga","8":"product_cat-recarga","10":"first","11":"outofstock","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/nbg.eu\/es\/wp-json\/wp\/v2\/product\/44945","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nbg.eu\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/nbg.eu\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nbg.eu\/es\/wp-json\/wp\/v2\/media\/27157"}],"wp:attachment":[{"href":"https:\/\/nbg.eu\/es\/wp-json\/wp\/v2\/media?parent=44945"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/nbg.eu\/es\/wp-json\/wp\/v2\/product_brand?post=44945"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/nbg.eu\/es\/wp-json\/wp\/v2\/product_cat?post=44945"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/nbg.eu\/es\/wp-json\/wp\/v2\/product_tag?post=44945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}