{"id":539585,"date":"2025-09-05T17:38:18","date_gmt":"2025-09-05T14:38:18","guid":{"rendered":"https:\/\/nbg.eu\/product\/or-leupold-delta-point-mounting-kit-for-l-02-w-02-steel-black\/"},"modified":"2026-04-16T19:05:32","modified_gmt":"2026-04-16T16:05:32","slug":"kit-de-montaje-or-leupold-delta-point-para-l-02-w-02-acero-negro","status":"publish","type":"product","link":"https:\/\/nbg.eu\/es\/producto\/kit-de-montaje-or-leupold-delta-point-para-l-02-w-02-acero-negro\/","title":{"rendered":"KMR OR Leupold Delta Point Kit de Montaje para L-02, W-02 Acero Negro"},"content":{"rendered":"<div class=\"product-description\">\n<h2>KIT DE MONTAJE OR LEUPOLD DELTA POINT PRO LW64<\/h2>\n<p><strong>Referencia:<\/strong> 0091-01207-0001<\/p>\n<p><strong>Marca:<\/strong> KMR Precision Arms<\/p>\n<h2>Descripci\u00f3n<\/h2>\n<p>El KIT DE MONTAJE OR LEUPOLD DELTA POINT PRO LW64 es para pistolas KMR L-02 o W-02. Esta placa base est\u00e1 dise\u00f1ada para modelos de pistola KMR L-02 y W-02 preparados para \u00f3pticas (OR), compatible con \u00f3pticas con huella Leupold DeltaPoint Pro.<\/p>\n<h2>Detalles del Producto<\/h2>\n<ul>\n<li>Material: Acero<\/li>\n<li>Color: Negro<\/li>\n<li>Incluye dos tornillos de instalaci\u00f3n M4<\/li>\n<\/ul>\n<h2>Instalaci\u00f3n<\/h2>\n<ol>\n<li>Desatornille la placa base original de la pistola<\/li>\n<li>Limpie cuidadosamente el \u00e1rea de montaje de la placa<\/li>\n<li>Instale la nueva placa base<\/li>\n<li>Apriete los dos tornillos M4 incluidos usando fijador de roscas<\/li>\n<\/ol>\n<p><strong>Importante:<\/strong> \u00a1NO USE LOCTITE ROJO!<\/p>\n<h2>Miras Punto Rojo Compatibles<\/h2>\n<p>Este kit de montaje es compatible con varias miras de punto rojo que comparten el est\u00e1ndar de montaje Leupold DeltaPoint Pro, incluyendo:<\/p>\n<ul>\n<li>Leupold DeltaPoint Pro<\/li>\n<li>Vortex Defender XL<\/li>\n<li>Eotech Eflx<\/li>\n<li>Holosun SCS 320<\/li>\n<li>Y muchos otros<\/li>\n<\/ul>\n<p>Este kit de montaje permite instalar su mira de punto rojo preferida en su pistola KMR L-02 o W-02.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Placa base de acero para pistolas KMR L-02\/W-02, compatible con \u00f3pticas DeltaPoint Pro<\/p>\n","protected":false},"featured_media":497560,"template":"","meta":{"_acf_changed":false},"product_brand":[11503],"product_cat":[12229],"product_tag":[],"class_list":{"0":"post-539585","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-kmr-precision","7":"product_cat-piezas-kmr","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/nbg.eu\/es\/wp-json\/wp\/v2\/product\/539585","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nbg.eu\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/nbg.eu\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nbg.eu\/es\/wp-json\/wp\/v2\/media\/497560"}],"wp:attachment":[{"href":"https:\/\/nbg.eu\/es\/wp-json\/wp\/v2\/media?parent=539585"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/nbg.eu\/es\/wp-json\/wp\/v2\/product_brand?post=539585"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/nbg.eu\/es\/wp-json\/wp\/v2\/product_cat?post=539585"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/nbg.eu\/es\/wp-json\/wp\/v2\/product_tag?post=539585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}