{"id":55804,"date":"2024-02-28T06:01:20","date_gmt":"2024-02-28T06:01:20","guid":{"rendered":"https:\/\/nbg.eu\/product\/fox-classic-hunter-9-3-mm-220-gr\/"},"modified":"2026-01-21T11:29:22","modified_gmt":"2026-01-21T08:29:22","slug":"fox-classic-hunter-93-mm-220-gr","status":"publish","type":"product","link":"https:\/\/nbg.eu\/es\/producto\/fox-classic-hunter-93-mm-220-gr\/","title":{"rendered":"Fox Classic Hunter 9.3 mm (220 gr)"},"content":{"rendered":"<div class=\"product-description\">\n<h2>Fox Classic Hunter<\/h2>\n<p>El Fox Classic Hunter es una bala sin plomo dise\u00f1ada para cazadores europeos en diversos escenarios de caza. Es adecuada para la caza de jabal\u00edes o de gamuzas en las monta\u00f1as. Esta bala de aleaci\u00f3n de cobre y zinc ofrece un rendimiento eficaz.<\/p>\n<ul>\n<li>Composici\u00f3n sin plomo<\/li>\n<li>Deformaci\u00f3n efectiva a velocidades de impacto m\u00e1s bajas (500 m\/s)<\/li>\n<li>Dise\u00f1o con ranuras para reducir la presi\u00f3n del ca\u00f1\u00f3n y aumentar la velocidad<\/li>\n<li>Punta de pl\u00e1stico termoestable que mejora la bal\u00edstica y el efecto terminal<\/li>\n<li>Expansi\u00f3n controlada para una transferencia de energ\u00eda \u00f3ptima<\/li>\n<li>Deformaci\u00f3n en forma de hongo hasta el doble del di\u00e1metro del calibre<\/li>\n<li>Alto poder de detenci\u00f3n con m\u00ednimo da\u00f1o a la carne<\/li>\n<\/ul>\n<p>El Fox Classic Hunter es una opci\u00f3n para la caza en Europa.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Bala de cobre-zinc sin plomo para caza vers\u00e1til. Expansi\u00f3n r\u00e1pida, alta precisi\u00f3n.<\/p>\n","protected":false},"featured_media":55805,"template":"","meta":{"_acf_changed":false},"product_brand":[11345],"product_cat":[12216,12265],"product_tag":[],"class_list":{"0":"post-55804","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-fox-bullets","7":"product_cat-balas","8":"product_cat-recarga","10":"first","11":"instock","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/nbg.eu\/es\/wp-json\/wp\/v2\/product\/55804","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nbg.eu\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/nbg.eu\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nbg.eu\/es\/wp-json\/wp\/v2\/media\/55805"}],"wp:attachment":[{"href":"https:\/\/nbg.eu\/es\/wp-json\/wp\/v2\/media?parent=55804"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/nbg.eu\/es\/wp-json\/wp\/v2\/product_brand?post=55804"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/nbg.eu\/es\/wp-json\/wp\/v2\/product_cat?post=55804"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/nbg.eu\/es\/wp-json\/wp\/v2\/product_tag?post=55804"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}