{"id":57274,"date":"2024-02-20T23:01:55","date_gmt":"2024-02-20T20:01:55","guid":{"rendered":"https:\/\/nbg.eu\/product\/geissele-ar15-super-precision-34mm-extended\/"},"modified":"2026-04-22T11:32:24","modified_gmt":"2026-04-22T08:32:24","slug":"ar15-super-precision-geissele-34mm-extendida","status":"publish","type":"product","link":"https:\/\/nbg.eu\/es\/producto\/ar15-super-precision-geissele-34mm-extendida\/","title":{"rendered":"Geissele Montaje para Mira AR15 Super Precision 34mm Extended"},"content":{"rendered":"<div class=\"product-description\">\n<h2>Geissele AR15 Super Precision\u00ae 34mm, Extendido<\/h2>\n<p>Mejore la precisi\u00f3n de su AR-15\/M4 con el montaje de mira Geissele Super Precision\u00ae 34mm Extendido. Este montaje incluye:<\/p>\n<ul>\n<li>7 secciones picatinny con 4 salientes de corte para estabilidad<\/li>\n<li>Sistema de sujeci\u00f3n con tuerca y perno, proporcionando 1,400 libras de fuerza por par<\/li>\n<li>Fabricado de una pieza de aluminio 7075-T6 de alta resistencia<\/li>\n<li>Rigidez mejorada mediante vaciados y nervaduras estrat\u00e9gicas<\/li>\n<li>Tapas perforadas en l\u00ednea para ajuste y protecci\u00f3n de la mira<\/li>\n<li>Tapas numeradas para garantizar la alineaci\u00f3n<\/li>\n<li>Dise\u00f1o vers\u00e1til para diversos tipos de miras<\/li>\n<\/ul>\n<p>Obtenga precisi\u00f3n al volver a cero y durabilidad con la ingenier\u00eda de Geissele.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Montaje de mira de 34mm para AR-15 con ingenier\u00eda de precisi\u00f3n para una estabilidad sin igual.<\/p>\n","protected":false},"featured_media":57276,"template":"","meta":{"_acf_changed":false},"product_brand":[11388],"product_cat":[14912,12279],"product_tag":[],"class_list":{"0":"post-57274","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-geissele","7":"product_cat-mounts-es","8":"product_cat-rifle","10":"first","11":"instock","12":"taxable","13":"shipping-taxable","14":"product-type-variable","15":"wvs-archive-product-wrapper"},"acf":[],"_links":{"self":[{"href":"https:\/\/nbg.eu\/es\/wp-json\/wp\/v2\/product\/57274","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nbg.eu\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/nbg.eu\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nbg.eu\/es\/wp-json\/wp\/v2\/media\/57276"}],"wp:attachment":[{"href":"https:\/\/nbg.eu\/es\/wp-json\/wp\/v2\/media?parent=57274"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/nbg.eu\/es\/wp-json\/wp\/v2\/product_brand?post=57274"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/nbg.eu\/es\/wp-json\/wp\/v2\/product_cat?post=57274"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/nbg.eu\/es\/wp-json\/wp\/v2\/product_tag?post=57274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}