{"id":62485,"date":"2024-02-13T20:10:34","date_gmt":"2024-02-13T20:10:34","guid":{"rendered":"https:\/\/nbg.eu\/product\/geissele-chf-chrome-lined-barrel-5-56-13-9\/"},"modified":"2026-04-22T12:13:22","modified_gmt":"2026-04-22T09:13:22","slug":"geissele-chf-canon-cromado-556-139","status":"publish","type":"product","link":"https:\/\/nbg.eu\/es\/producto\/geissele-chf-canon-cromado-556-139\/","title":{"rendered":"Geissele Ca\u00f1\u00f3n CHF Chrome Lined 5.56 &#8211; 13.9&#8243;"},"content":{"rendered":"<div class=\"product-description\">\n<h2>Ca\u00f1\u00f3n Geissele CHF Cromado &#8211; 5.56 <\/h2>\n<p>El ca\u00f1\u00f3n Geissele CHF cromado en 5.56 NATO est\u00e1 fabricado en North Wales, PA, combinando tecnolog\u00eda avanzada con artesan\u00eda.<\/p>\n<ul>\n<li>Forjado en fr\u00edo (CHF) para mayor resistencia y durabilidad<\/li>\n<li>Cromado para mayor resistencia a la corrosi\u00f3n y facilidad de limpieza<\/li>\n<li>Probado a alta presi\u00f3n (HPT) e inspeccionado por part\u00edculas magn\u00e9ticas (MPI) para garant\u00eda de calidad<\/li>\n<li>Adecuado para armas de servicio, armas de competici\u00f3n y otros usos<\/li>\n<li>Mecanizado de precisi\u00f3n con materiales de alta calidad para consistencia y precisi\u00f3n<\/li>\n<\/ul>\n<p>Elija Geissele para un rendimiento en cualquier situaci\u00f3n.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ca\u00f1\u00f3n de 5,56 forjado con precisi\u00f3n. Probado con HPT\/MPI para mayor fiabilidad.<\/p>\n","protected":false},"featured_media":62486,"template":"","meta":{"_acf_changed":false},"product_brand":[11388],"product_cat":[12280,12211,12279,12240],"product_tag":[],"class_list":{"0":"post-62485","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-geissele","7":"product_cat-canones","8":"product_cat-carabinas","9":"product_cat-rifle","10":"product_cat-tuning-de-rifle","12":"first","13":"instock","14":"taxable","15":"shipping-taxable","16":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/nbg.eu\/es\/wp-json\/wp\/v2\/product\/62485","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nbg.eu\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/nbg.eu\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nbg.eu\/es\/wp-json\/wp\/v2\/media\/62486"}],"wp:attachment":[{"href":"https:\/\/nbg.eu\/es\/wp-json\/wp\/v2\/media?parent=62485"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/nbg.eu\/es\/wp-json\/wp\/v2\/product_brand?post=62485"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/nbg.eu\/es\/wp-json\/wp\/v2\/product_cat?post=62485"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/nbg.eu\/es\/wp-json\/wp\/v2\/product_tag?post=62485"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}